{"id":25239,"date":"2020-11-04T06:27:08","date_gmt":"2020-11-04T05:27:08","guid":{"rendered":"https:\/\/educacio-valencia.es\/abrazar-la-diversidad\/"},"modified":"2020-11-04T06:27:08","modified_gmt":"2020-11-04T05:27:08","slug":"abrazar-la-diversidad","status":"publish","type":"post","link":"https:\/\/educacio-valencia.es\/es\/abrazar-la-diversidad\/","title":{"rendered":"Abrazar la diversidad"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-first\" style=\"width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><img width=\"958\" height=\"716\" src=\"https:\/\/educacio-valencia.es\/wp-content\/uploads\/2020\/11\/Abrazar-la-diversidad.png\" class=\" wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/educacio-valencia.es\/wp-content\/uploads\/2020\/11\/Abrazar-la-diversidad-200x149.png 200w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2020\/11\/Abrazar-la-diversidad-300x224.png 300w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2020\/11\/Abrazar-la-diversidad-400x299.png 400w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2020\/11\/Abrazar-la-diversidad-600x448.png 600w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2020\/11\/Abrazar-la-diversidad-768x574.png 768w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2020\/11\/Abrazar-la-diversidad-800x598.png 800w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2020\/11\/Abrazar-la-diversidad.png 958w\" sizes=\"(max-width: 958px) 100vw, 958px\" \/><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-last\" style=\"width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1 fusion-text-split-columns fusion-text-columns-2\" style=\" -webkit-column-count:2; -webkit-column-gap:2em; -webkit-column-width:100px; -moz-column-count:2; -moz-column-gap:2em; -moz-column-width:100px; column-count:2; column-gap:2em; column-width:100px;transform:translate3d(0,0,0);\"><h1>Abrazar la diversidad<\/h1>\n<p>Esta extensa y completa gu\u00eda forma parte del Proyecto \u00abConociendo la Discriminaci\u00f3n, Reconociendo la Diversidad\u00bb (CORE), que puerta adelante el Instituto de la Mujer y para la Igualdad de Oportunidades como parte del Programa Europeo para la Ocupaci\u00f3n y la Solidaridad Social (PROGRESS) de la Direcci\u00f3n General de Justicia de la Comisi\u00f3n Europea.<\/p>\n<p>En ella se hacen propuestas para una educaci\u00f3n libre de acoso homof\u00f3bico y transf\u00f3bico.<\/p>\n<p>Podemos encontrar:<\/p>\n<p>1. Un an\u00e1lisis conceptual y de incidencia que explica los principales conceptos y caracter\u00edsticas relativas a la diversidad sexual, familiar y de identidad de g\u00e9nero, as\u00ed como la especificidad e incidencia del acoso escolar por homofobia y transfobia.<br \/>\n2. Un apartado que recoge algunas buenas pr\u00e1cticas de atenci\u00f3n a la diversidad sexual, familiar y de identidad de g\u00e9nero a nivel internacional, estatal y de centros escolares.<br \/>\n3. Una gu\u00eda de acci\u00f3n contra el acoso en los centros educativos que ofrece recomendaciones para prevenir, indicadores para detectar y un protocolo para enfrentar el acoso escolar por homofobia y transfobia.<br \/>\n4.Una gu\u00eda de recursos did\u00e1cticos para la cual se han seleccionado, entre m\u00e1s de 200 recursos revisados, medio centenar de ellos organizados de acuerdo con el nivel educativo, caracter\u00edsticas y formato.<br \/>\n5. Un an\u00e1lisis del marco normativo espa\u00f1ol que sustenta el mandato legal de impedir el acoso escolar por homofobia y transfobia.<br \/>\n6.Una recopilaci\u00f3n de las pol\u00edticas p\u00fablicas y normativas legales en cada una de las comunidades aut\u00f3nomas, responsables de la educaci\u00f3n a nuestro pa\u00eds.<br \/>\n7. Una serie de anexos con modelos que se pueden utilizar de manera directa o adaptada para poner en marcha algunas de las propuestas del documento. Como anexo se recogen tambi\u00e9n las referencias citadas a lo largo de los diferentes apartados del texto.<\/p>\n<p><strong>Recomendado:<\/strong> EI\/EP\/ESO\/Bachillerato<\/p>\n<p><strong>Enlace:<\/strong><\/p>\n<p><a href=\"https:\/\/www.inmujer.gob.es\/actualidad\/NovedadesNuevas\/docs\/2015\/Abrazar_la_diversidad.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><strong>Abrazar la diversidad<\/strong><\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"author":15,"featured_media":25240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[181,189],"tags":[],"_links":{"self":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/posts\/25239"}],"collection":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/comments?post=25239"}],"version-history":[{"count":0,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/posts\/25239\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/media\/25240"}],"wp:attachment":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/media?parent=25239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/categories?post=25239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/tags?post=25239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}