{"id":44136,"date":"2025-07-02T12:01:31","date_gmt":"2025-07-02T10:01:31","guid":{"rendered":"https:\/\/educacio-valencia.es\/?post_type=avada_portfolio&#038;p=44136"},"modified":"2026-07-02T09:28:05","modified_gmt":"2026-07-02T07:28:05","slug":"con-la-musica-a-todas-partes-nota-a-nota-emocion-a-emocion","status":"publish","type":"avada_portfolio","link":"https:\/\/educacio-valencia.es\/es\/proyectos\/con-la-musica-a-todas-partes-nota-a-nota-emocion-a-emocion\/","title":{"rendered":"Con la m\u00fasica a todas partes. Nota a nota, emoci\u00f3n a emoci\u00f3n"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 bloqueSeccion nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:10px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"margin-top:0px;margin-bottom:10px;\"><h2 class=\"title-heading-left\" style=\"margin:0;\"><h2>Con la m\u00fasica a todas partes. Nota a nota, emoci\u00f3n a emoci\u00f3n<\/h2><\/h2><\/div><div class=\"fusion-text fusion-text-1\" style=\"transform:translate3d(0,0,0);\"><p>Este a\u00f1o el Ayuntamiento de Val\u00e8ncia pone la M\u00fasica en el centro de las propuestas culturales de la ciudad.<\/p>\n<p>Teniendo como base la tradici\u00f3n musical de Val\u00e8ncia y en el importante ecosistema generado a trav\u00e9s de a\u00f1os se ha elegido este lenguaje como veh\u00edculo de comunicaci\u00f3n, de entendimiento y de integraci\u00f3n de la diversidad.<\/p>\n<p>Proyectos Educativos acompa\u00f1a esta elecci\u00f3n poniendo a disposici\u00f3n de la comunidad educativa el proyecto <b>Con la m\u00fasica a todas partes<\/b>.<\/p>\n<p>La presente iniciativa se estructura en 2 programas a desarrollar en el aula, independientes los unos de los otros.<\/p>\n<p>Los centros educativos podr\u00e1n solicitar de manera individual o conjunta cada uno de los programas. Cada propuesta abordar\u00e1 la intersecci\u00f3n entre la m\u00fasica y el \u00e1rea tem\u00e1tica del bloque de contenido en el que se encuentre<\/p>\n<h3>Programas del proyecto <b>Con la m\u00fasica a todas partes:<\/b>.<\/h3>\n<ul>\n<li><strong>Con la m\u00fasica a todas partes. Nota a nota, emoci\u00f3n a emoci\u00f3n.<\/strong><\/li>\n<li><a href=\"https:\/\/educacio-valencia.es\/es\/proyectos\/con-la-musica-a-todas-partes-la-musica-como-patrimonio-inmaterial\/\"><strong>Con la m\u00fasica a todas partes. La m\u00fasica como patrimonio inmaterial<\/strong><\/a><\/li>\n<\/ul>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none imgCabeceraSeccion\"><img width=\"987\" height=\"658\" title=\"definitivo emociones\" src=\"https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/definitivo-emociones.png\" class=\"img-responsive wp-image-44388\" srcset=\"https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/definitivo-emociones-200x133.png 200w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/definitivo-emociones-400x267.png 400w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/definitivo-emociones-600x400.png 600w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/definitivo-emociones-800x533.png 800w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/definitivo-emociones.png 987w\" sizes=\"(max-width: 800px) 100vw, 987px\" \/><\/span><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Descripci\u00f3n<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-2\" style=\"transform:translate3d(0,0,0);\"><p>\u201cNota a nota, emoci\u00f3n a emoci\u00f3n\u201d es un programa educativo vivencial que utiliza la m\u00fasica como herramienta para trabajar la educaci\u00f3n emocional con el alumnado de Educaci\u00f3n Primaria.<\/p>\n<p>A trav\u00e9s de actividades de escucha musical, movimiento, expresi\u00f3n corporal y reflexi\u00f3n compartida, el alumnado aprende a identificar, expresar y regular sus emociones de manera adecuada. La m\u00fasica se convierte as\u00ed en un recurso cercano y motivador que facilita la conexi\u00f3n con lo que cada persona siente y ayuda a mejorar la convivencia en el aula.<\/p>\n<p>El programa se desarrolla mediante una metodolog\u00eda activa, participativa y cooperativa, adaptada a la edad del alumnado. Las actividades propuestas permiten trabajar la conciencia emocional, la escucha respetuosa, la relaci\u00f3n con las dem\u00e1s personas y el bienestar personal y grupal.<\/p>\n<p>De este modo, \u201cNota a nota, emoci\u00f3n a emoci\u00f3n\u201d ofrece al alumnado una experiencia educativa significativa en la que m\u00fasica y emociones se unen para favorecer su desarrollo emocional, ayud\u00e1ndole a reconocer qu\u00e9 siente ante diferentes propuestas musicales y c\u00f3mo esas emociones pueden influir en su forma de actuar y relacionarse.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Objetivos<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-3\" style=\"transform:translate3d(0,0,0);\"><p>\u2022 Favorecer la conciencia emocional a trav\u00e9s de experiencias musicales significativas.<br \/>\n\u2022 Desarrollar estrategias de regulaci\u00f3n emocional mediante la m\u00fasica.<br \/>\n\u2022 Fomentar la autonom\u00eda emocional y la autoestima a trav\u00e9s de la expresi\u00f3n musical.<br \/>\n\u2022 Potenciar la empat\u00eda y la competencia social<br \/>\n\u2022 Promover el bienestar y la reflexi\u00f3n emocional en el entorno escolar.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Dirigido a<\/strong><\/h4><\/div>EP1, EP2, EP3, EP4, EP5, EP6<div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Calendario y horario<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-4\" style=\"transform:translate3d(0,0,0);\"><p>\u2022 El programa consta de dos sesiones de una hora y media de duraci\u00f3n cada una.<br \/>\n\u2022 A lo largo del a\u00f1o escolar, en horario lectivo.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-6 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Aportaciones del Ayuntamiento<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-5\" style=\"transform:translate3d(0,0,0);\"><p>\u2022 Equipo t\u00e9cnico de la Secci\u00f3n de Proyectos Educativos para la elaboraci\u00f3n, organizaci\u00f3n y coordinaci\u00f3n del Programa.<br \/>\n\u2022 Personal educador.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-7 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Observaciones<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-6\" style=\"transform:translate3d(0,0,0);\"><p>Se realiza en las instalaciones del propio centro educativo.<\/p>\n<p>Al finalizar la actividad educativa el profesorado responsable del grupo, as\u00ed como el alumnado participante, cumplimentaran el cuestionario de evaluaci\u00f3n de calidad.\u00a0 Este cuestionario se cumplimenta on-line. Los enlaces para su acceso se encuentran al final de cada uno de los programas recopilados en la web de educaci\u00f3n.<\/p>\n<h3><span style=\"font-family: Montserrat; letter-spacing: -.1pt;\">Requisitos para su ejecuci\u00f3n<\/span><\/h3>\n<ul>\n<li>El aula deber\u00e1:\n<ul>\n<li>posibilitar el movimiento del alumnado en momentos puntuales<\/li>\n<li>disponer de ordenador para el equipo docente con acceso a internet y los recursos digitales online que se utilicen durante la ejecuci\u00f3n de la actividad.<\/li>\n<li>disponer de pantalla electr\u00f3nica o proyector con altavoces que permita visualizar y escuchar las piezas musicales propuestas en las actividades.<\/li>\n<\/ul>\n<\/li>\n<li>Para la realizaci\u00f3n de algunas actividades del programa, ser\u00e1 necesario que el alumnado disponga de material b\u00e1sico de uso habitual en el aula, como folios, l\u00e1pices, colores, rotuladores u otros recursos similares.<\/li>\n<\/ul>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-8 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Informaci\u00f3n<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-7\" style=\"transform:translate3d(0,0,0);\"><p>email: sccproyectosed@valencia.es<\/p>\n<p>962084283 \u2013 962082146<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-17 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-9 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Cuestionarios de evaluaci\u00f3n<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-8\" style=\"transform:translate3d(0,0,0);\"><ul>\n<li>Cuestionario de evaluaci\u00f3n docente \u00a0\u00a0 \u00a0\u00a0<strong><a href=\"https:\/\/forms.gle\/23CXMAZeL2BXakYT8\">https:\/\/forms.gle\/23CXMAZeL2BXakYT8<\/a><\/strong><\/li>\n<li>Cuestionario de evaluaci\u00f3n alumnado \u00a0<strong><a href=\"https:\/\/forms.gle\/J4eWJ8WZ5HFuvwKA9\">https:\/\/forms.gle\/J4eWJ8WZ5HFuvwKA9<\/a><\/strong><\/li>\n<\/ul>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-18 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-19 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-10 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>ODS relacionados con el programa<\/strong><\/h4><\/div><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img width=\"60\" height=\"60\" title=\"Gui\u0301a-ODS-Universidades\" src=\"http:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/Gui\u0301a-ODS-Universidades.png\" class=\"img-responsive wp-image-14983\"\/><\/span><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img width=\"60\" height=\"60\" title=\"Imprimir\" src=\"https:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/ODS-3.jpg\" class=\"img-responsive wp-image-15010\"\/><\/span><span class=\" fusion-imageframe imageframe-none imageframe-4 hover-type-none\"><img width=\"60\" height=\"60\" title=\"S_SDG goals_icons-individual-rgb-04\" src=\"http:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/S_SDG-goals_icons-individual-rgb-04.png\" class=\"img-responsive wp-image-14996\"\/><\/span><span class=\" fusion-imageframe imageframe-none imageframe-5 hover-type-none\"><img width=\"60\" height=\"60\" title=\"Imprimir\" src=\"https:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/ODS-5.jpg\" class=\"img-responsive wp-image-15012\"\/><\/span><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-20 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-21 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 10px 0px 0px 0px;\"><span class=\" fusion-imageframe imageframe-none imageframe-6 hover-type-none\"><img width=\"510\" height=\"77\" alt=\"Logotipo de la Regidoria de Educaci\u00f3n.\" title=\"Logo city ayu transparente\" src=\"https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/Logo-city-ayu-transparente.png\" class=\"img-responsive wp-image-44578\" srcset=\"https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/Logo-city-ayu-transparente-200x30.png 200w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/Logo-city-ayu-transparente-400x60.png 400w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/Logo-city-ayu-transparente.png 510w\" sizes=\"(max-width: 800px) 100vw, 510px\" \/><\/span><span class=\" fusion-imageframe imageframe-none imageframe-7 hover-type-none\"><img width=\"400\" height=\"206\" title=\"logo Conselleria de Educaci\u00f3n, Cultura, Universidades y Empleo 2025\" src=\"https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/logo-Conselleria-de-Educacion-Cultura-Universidades-y-Empleo-2025-400x206.png\" class=\"img-responsive wp-image-44479\" srcset=\"https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/logo-Conselleria-de-Educacion-Cultura-Universidades-y-Empleo-2025-200x103.png 200w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/logo-Conselleria-de-Educacion-Cultura-Universidades-y-Empleo-2025-400x206.png 400w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/logo-Conselleria-de-Educacion-Cultura-Universidades-y-Empleo-2025-600x309.png 600w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/logo-Conselleria-de-Educacion-Cultura-Universidades-y-Empleo-2025-800x413.png 800w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/logo-Conselleria-de-Educacion-Cultura-Universidades-y-Empleo-2025-1200x619.png 1200w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2025\/07\/logo-Conselleria-de-Educacion-Cultura-Universidades-y-Empleo-2025.png 1369w\" sizes=\"(max-width: 800px) 100vw, 400px\" \/><\/span><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es un programa educativo vivencial, centrado en la educaci\u00f3n emocional a trav\u00e9s de la m\u00fasica. Su objetivo principal es proporcionar al alumnado experiencias significativas donde la m\u00fasica sea una herramienta para explorar, identificar, expresar y regular sus emociones.<\/p>\n","protected":false},"author":8,"featured_media":44388,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":[],"portfolio_category":[12,10],"portfolio_skills":[22,23,24,25,26,27],"portfolio_tags":[],"_links":{"self":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/avada_portfolio\/44136"}],"collection":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/comments?post=44136"}],"version-history":[{"count":20,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/avada_portfolio\/44136\/revisions"}],"predecessor-version":[{"id":47515,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/avada_portfolio\/44136\/revisions\/47515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/media\/44388"}],"wp:attachment":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/media?parent=44136"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/portfolio_category?post=44136"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/portfolio_skills?post=44136"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/portfolio_tags?post=44136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}