{"id":11501,"date":"2019-07-10T12:29:41","date_gmt":"2019-07-10T10:29:41","guid":{"rendered":"http:\/\/educacio-valencia.es\/?post_type=avada_portfolio&#038;p=11501"},"modified":"2019-09-09T09:40:19","modified_gmt":"2019-09-09T07:40:19","slug":"obrint-nos-als-barris","status":"publish","type":"avada_portfolio","link":"https:\/\/educacio-valencia.es\/es\/proyectos\/obrint-nos-als-barris\/","title":{"rendered":"Obrint-nos als Barris"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 bloqueSeccion nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:10px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"margin-top:0px;margin-bottom:10px;\"><h2 class=\"title-heading-left\" style=\"margin:0;\"><strong>Obrint-nos als Barris<\/strong><\/h2><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none imgCabeceraSeccion\"><img width=\"424\" height=\"542\" alt=\"VALENTIA, la vida en una ciudad romana\" title=\"Abcbarris\" src=\"http:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/Abcbarris.jpg\" class=\"img-responsive wp-image-14937\" srcset=\"https:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/Abcbarris-200x256.jpg 200w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/Abcbarris-400x511.jpg 400w, https:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/Abcbarris.jpg 424w\" sizes=\"(max-width: 800px) 100vw, 424px\" \/><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Descripci\u00f3n<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-1\" style=\"transform:translate3d(0,0,0);\"><p>Con la aprobaci\u00f3n en el mes de marzo del Plan de Juventud 2019-2023, se quiere dar a conocer y acercar los Centros Municipales de Juventud (CMJ) a los centros educativos de la ciudad.<br \/>\nLos CMJ son espacios p\u00fablicos, abiertos a la totalidad de las personas j\u00f3venes, cuyo objetivo es la generaci\u00f3n de procesos de participaci\u00f3n social que conviertan a las personas j\u00f3venes en ciudadan\u00eda activa y cr\u00edtica a trav\u00e9s del desarrollo de una acci\u00f3n educativa en valores (la tolerancia, el respeto, la igualdad, la justicia social\u2026) y una acci\u00f3n socializadora.<br \/>\nEl personal t\u00e9cnico del CMJ de barrio se pone en contacto con el centro educativo solicitante, para realizar las diferentes acciones de la campa\u00f1a.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Objetivos<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-2\" style=\"transform:translate3d(0,0,0);\"><ul>\n<li>Iniciar y fortalecer las relaciones entre los CMJ y los centros educativos.<\/li>\n<li>Dar a conocer los CMJ como recurso tanto para las personas j\u00f3venes (alumnado de 11 a 20 a\u00f1os) como para todos los agentes implicados en la vida de los barrios (comunidad escolar).<\/li>\n<li>Fomentar la participaci\u00f3n, la autonom\u00eda y la colaboraci\u00f3n del alumnado.<\/li>\n<li>Crear en los centros educativos PIJ (Puntos de Informaci\u00f3n Juvenil).<\/li>\n<li>Crear una red de corresponsales juveniles.<\/li>\n<li>Potenciar el asociacionismo y el voluntariado juvenil.<\/li>\n<li>Crear herramientas que permitan detectar posibles problemas que surgen en las interacciones entre los y las j\u00f3venes y en la convivencia en sociedad.<\/li>\n<\/ul>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Dirigido a<\/strong><\/h4><\/div>BC1, BC2, CFS, EP6, ESO1, ESO2, ESO3, ESO4<div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Calendario y Horario<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-3\" style=\"transform:translate3d(0,0,0);\"><p>Esta campa\u00f1a consta de diversas acciones\/actividades a realizar en el propio centro y en el CMJ del barrio, pudi\u00e9ndose realizar todas las que se proponen o solo algunas.<\/p>\n<h3 style=\"text-align: center;\"><strong>A la hora de realizar la inscripci\u00f3n debe indicar en el apartado de &#8220;OBSERVACIONES&#8221; la actividad o actividades que quiere solicitar.<\/strong><\/h3>\n<ol>\n<li><strong>\u201cDinamizaci\u00f3n de patios de recreo\u201d<\/strong>. Sesi\u00f3n\/es de ocio saludable y creativo en los espacios de recreo dentro del horario lectivo. Dirigida al alumnado de 6\u00ba de EP, 1\u00ba, 2\u00ba, 3\u00ba y 4\u00ba de la ESO y para cualquier otro nivel de educaci\u00f3n secundaria.<\/li>\n<li><strong>\u201cConoce tu CMJ\u201d<\/strong> Sesi\u00f3n, en horario de tutor\u00eda, para dar a conocer, con material audiovisual (V\u00eddeo Plan de Juventud, v\u00eddeo Infosex, v\u00eddeo CMJ) y diversas din\u00e1micas, el CMJ del barrio. Dirigida al alumnado de 6\u00ba de EP, 1\u00ba, 2\u00ba, 3\u00ba y 4\u00ba de la ESO y para cualquier otro nivel de educaci\u00f3n secundaria.<\/li>\n<li><strong>\u201cVisita tu CMJ\u201d<\/strong>. Dar a conocer las instalaciones y servicios que ofrece el CMJ, y realizar diferentes actividades \/ talleres. Dirigida al alumnado de 6\u00ba de EP, 1\u00ba, 2\u00ba, 3\u00ba y 4\u00ba de la ESO y para cualquier otro nivel de educaci\u00f3n secundaria.<\/li>\n<li><strong>\u201cPaseo por la web JuventudVLC\u201d<\/strong> Sesi\u00f3n en horario de tutor\u00eda y en el aula de inform\u00e1tica del centro, que consiste en realizar una visita virtual, guiada, por la web de Juventud. Dirigida al alumnado de 6\u00ba de EP, 1\u00ba, 2\u00ba, 3\u00ba y 4\u00ba de la ESO y para cualquier otro nivel de educaci\u00f3n secundaria.<\/li>\n<li><strong>\u201cCarnet Jove\u201d<\/strong>. Sesi\u00f3n en el centro educativo para explicar las ventajas que tiene tener el Carnet Jove y orientar c\u00f3mo tramitarlo. Dirigida al alumnado de 6\u00ba de EP, 1\u00ba, 2\u00ba, 3\u00ba y 4\u00ba de la ESO y para cualquier otro nivel de educaci\u00f3n secundaria.<\/li>\n<li><strong>\u201cSom corresponsals!\u201d<\/strong>. Las y los corresponsales de juventud son alumnado que cursa sus estudios de ESO, Bachillerato y CF en colegios e institutos. Su funci\u00f3n es la de hacer llegar la informaci\u00f3n, recursos y servicios (asociacionismo, voluntariado, ocio, becas\u2026) que ata\u00f1en a la juventud al resto de compa\u00f1eras y compa\u00f1eros de sus respectivas aulas y proporcionar a su vez informaci\u00f3n de sus inquietudes al CMJ. Esta actividad requiere varias sesiones a lo largo del curso escolar. Dirigida al alumnado de 1\u00ba, 2\u00ba, 3\u00ba y 4\u00ba de la ESO y para cualquier otro nivel de educaci\u00f3n secundaria.<\/li>\n<li><strong>Implantaci\u00f3n del \u201cPunt Jove\u201d (PIJ).<\/strong> Un PIJ (Punto de Informaci\u00f3n Juvenil) consiste b\u00e1sicamente en la localizaci\u00f3n estrat\u00e9gica de un espacio permanente, t\u00f3tem o panel de corcho, y una alumna o alumno responsable de colgar y actualizar informaci\u00f3n juvenil, y actividades y servicios a disposici\u00f3n de la poblaci\u00f3n del centro educativo.<\/li>\n<\/ol>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-6 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Aportaciones del Ayuntamiento<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-4\" style=\"transform:translate3d(0,0,0);\"><ul>\n<li>Personal cualificado (Educador\/a \/ TASOCT)<\/li>\n<li>Material de trabajo necesario para las sesiones de trabajo.<\/li>\n<\/ul>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-7 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>Informaci\u00f3n<\/strong><\/h4><\/div><div class=\"fusion-text fusion-text-5\" style=\"transform:translate3d(0,0,0);\"><p>962085231 \/ 962087103<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-8 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:10px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><strong>ODS relacionados con el programa<\/strong><\/h4><\/div><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img width=\"60\" height=\"60\" title=\"Gui\u0301a-ODS-Universidades\" src=\"http:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/Gui\u0301a-ODS-Universidades.png\" class=\"img-responsive wp-image-14983\"\/><\/span><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img width=\"60\" height=\"60\" title=\"S_SDG goals_icons-individual-rgb-04\" src=\"http:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/S_SDG-goals_icons-individual-rgb-04.png\" class=\"img-responsive wp-image-14996\"\/><\/span><span class=\" fusion-imageframe imageframe-none imageframe-4 hover-type-none\"><img width=\"60\" height=\"60\" title=\"S_SDG goals_icons-individual-rgb-11\" src=\"http:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/S_SDG-goals_icons-individual-rgb-11.png\" class=\"img-responsive wp-image-14986\"\/><\/span><span class=\" fusion-imageframe imageframe-none imageframe-5 hover-type-none\"><img width=\"60\" height=\"60\" title=\"S_SDG goals_icons-individual-rgb-16\" src=\"http:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/S_SDG-goals_icons-individual-rgb-16.png\" class=\"img-responsive wp-image-14991\"\/><\/span><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion_builder_column_2_5 2_5 fusion-two-fifth fusion-column-first\" style=\"width:40%;width:calc(40% - ( ( 4% ) * 0.4 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-17 fusion_builder_column_3_5 3_5 fusion-three-fifth fusion-column-last bloqueSeccion marginCero\" style=\"width:60%;width:calc(60% - ( ( 4% ) * 0.6 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 10px 0px 0px 0px;\"><span class=\" fusion-imageframe imageframe-none imageframe-6 hover-type-none\"><img width=\"300\" height=\"43\" alt=\"Logotipo de la Regidoria de Educaci\u00f3n.\" title=\"Logo Joventut CMJ\" src=\"http:\/\/educacio-valencia.es\/wp-content\/uploads\/2019\/07\/Logo-Joventut-CMJ-e1562754729678.jpg\" class=\"img-responsive wp-image-14938\"\/><\/span><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-18 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"margin-top:0px;margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-6\" style=\"transform:translate3d(0,0,0);\"><p>&nbsp;<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la aprobaci\u00f3n en el mes de marzo del Plan de Juventud 2019-2023, se quiere dar a conocer y acercar los Centros Municipales de Juventud (CMJ) a los centros educativos de la ciudad.<\/p>\n","protected":false},"author":8,"featured_media":11504,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":[],"portfolio_category":[10,11],"portfolio_skills":[34,35,36,27,28,29,30,31],"portfolio_tags":[],"_links":{"self":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/avada_portfolio\/11501"}],"collection":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/comments?post=11501"}],"version-history":[{"count":7,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/avada_portfolio\/11501\/revisions"}],"predecessor-version":[{"id":13321,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/avada_portfolio\/11501\/revisions\/13321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/media\/11504"}],"wp:attachment":[{"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/media?parent=11501"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/portfolio_category?post=11501"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/portfolio_skills?post=11501"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/educacio-valencia.es\/es\/wp-json\/wp\/v2\/portfolio_tags?post=11501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}